{"id":12817,"date":"2026-09-01T18:24:03","date_gmt":"2026-09-01T21:24:03","guid":{"rendered":"https:\/\/selvagemciclo.org.br\/?post_type=tribe_events&#038;p=12817"},"modified":"2026-09-01T18:24:03","modified_gmt":"2026-09-01T21:24:03","slug":"sopro-dos-dragoes-franca-3","status":"publish","type":"tribe_events","link":"https:\/\/selvagemciclo.org.br\/en\/agenda\/sopro-dos-dragoes-franca-3\/","title":{"rendered":"Sopro dos drag\u00f5es &#8211; Fran\u00e7a"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Entre os dias 9 e 12 de setembro, acontece a s\u00e9rie de encontros \u201cO sopro dos drag\u00f5es: Di\u00e1logos interdisciplinares em torno das pot\u00eancias elementares\u201d, organizada pela Associa\u00e7\u00e3o Selvagem junto com a Universidade Sorbonne, \u00e0 convite da antrop\u00f3loga Nastassja Martin. O evento inclui 3 dias de programa\u00e7\u00e3o no Museu Departamental Albert-Kahn, em Paris, com falas de Cristine Taku\u00e1, Anna Dantes e Carlos Pap\u00e1, e uma noite no cinema com filmes da cole\u00e7\u00e3o KADIST e com as Flechas Selvagem, exibidas em di\u00e1logo com os artistas. O evento \u00e9 presencial e as inscri\u00e7\u00f5es s\u00e3o gratuitas.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Entre os dias 9 e 12 de setembro, acontece a s\u00e9rie de encontros \u201cO sopro dos drag\u00f5es: Di\u00e1logos interdisciplinares em torno das pot\u00eancias elementares\u201d, organizada pela Associa\u00e7\u00e3o Selvagem junto com a Universidade Sorbonne, \u00e0 convite da antrop\u00f3loga Nastassja Martin. O evento inclui 3 dias de programa\u00e7\u00e3o no Museu Departamental Albert-Kahn, em Paris, com falas de Cristine Taku\u00e1, Anna Dantes e Carlos Pap\u00e1, e uma noite no cinema com filmes da cole\u00e7\u00e3o KADIST e com as Flechas Selvagem, exibidas em di\u00e1logo com os artistas. O evento \u00e9 presencial e as inscri\u00e7\u00f5es s\u00e3o gratuitas.<\/p>","protected":false},"author":2,"featured_media":12741,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[8],"class_list":["post-12817","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","tribe_events_cat-encontros-presenciais","cat_encontros-presenciais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sopro dos drag\u00f5es - Fran\u00e7a - Selvagem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/selvagemciclo.org.br\/en\/agenda\/sopro-dos-dragoes-franca-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sopro dos drag\u00f5es - Fran\u00e7a - Selvagem\" \/>\n<meta property=\"og:description\" content=\"Entre os dias 9 e 12 de setembro, acontece a s\u00e9rie de encontros \u201cO sopro dos drag\u00f5es: Di\u00e1logos interdisciplinares em torno das pot\u00eancias elementares\u201d, organizada pela Associa\u00e7\u00e3o Selvagem junto com a Universidade Sorbonne, \u00e0 convite da antrop\u00f3loga Nastassja Martin. O evento inclui 3 dias de programa\u00e7\u00e3o no Museu Departamental Albert-Kahn, em Paris, com falas de Cristine Taku\u00e1, Anna Dantes e Carlos Pap\u00e1, e uma noite no cinema com filmes da cole\u00e7\u00e3o KADIST e com as Flechas Selvagem, exibidas em di\u00e1logo com os artistas. O evento \u00e9 presencial e as inscri\u00e7\u00f5es s\u00e3o gratuitas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/selvagemciclo.org.br\/en\/agenda\/sopro-dos-dragoes-franca-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Selvagem\" \/>\n<meta property=\"og:image\" content=\"https:\/\/selvagemciclo.org.br\/wp-content\/uploads\/2026\/08\/SD_LOGO2-e1787863731989.png\" \/>\n\t<meta property=\"og:image:width\" content=\"906\" \/>\n\t<meta property=\"og:image:height\" content=\"906\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/selvagemciclo.org.br\\\/agenda\\\/sopro-dos-dragoes-franca-3\\\/\",\"url\":\"https:\\\/\\\/selvagemciclo.org.br\\\/agenda\\\/sopro-dos-dragoes-franca-3\\\/\",\"name\":\"Sopro dos drag\u00f5es - Fran\u00e7a - Selvagem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selvagemciclo.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/selvagemciclo.org.br\\\/agenda\\\/sopro-dos-dragoes-franca-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/selvagemciclo.org.br\\\/agenda\\\/sopro-dos-dragoes-franca-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selvagemciclo.org.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/SD_LOGO2-e1787863731989.png\",\"datePublished\":\"2026-09-01T21:24:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/selvagemciclo.org.br\\\/agenda\\\/sopro-dos-dragoes-franca-3\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/selvagemciclo.org.br\\\/agenda\\\/sopro-dos-dragoes-franca-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/selvagemciclo.org.br\\\/agenda\\\/sopro-dos-dragoes-franca-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/selvagemciclo.org.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/SD_LOGO2-e1787863731989.png\",\"contentUrl\":\"https:\\\/\\\/selvagemciclo.org.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/SD_LOGO2-e1787863731989.png\",\"width\":906,\"height\":906,\"caption\":\"O Sopro dos Drag\u00f5es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/selvagemciclo.org.br\\\/agenda\\\/sopro-dos-dragoes-franca-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/selvagemciclo.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/selvagemciclo.org.br\\\/agenda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sopro dos drag\u00f5es &#8211; Fran\u00e7a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/selvagemciclo.org.br\\\/#website\",\"url\":\"https:\\\/\\\/selvagemciclo.org.br\\\/\",\"name\":\"Selvagem\",\"description\":\"Ciclo de estudos sobre a vida\",\"publisher\":{\"@id\":\"https:\\\/\\\/selvagemciclo.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/selvagemciclo.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/selvagemciclo.org.br\\\/#organization\",\"name\":\"Selvagem\",\"url\":\"https:\\\/\\\/selvagemciclo.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/selvagemciclo.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/selvagemciclo.org.br\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-ICONE_SELVAGEM_2026-1.png\",\"contentUrl\":\"https:\\\/\\\/selvagemciclo.org.br\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-ICONE_SELVAGEM_2026-1.png\",\"width\":512,\"height\":512,\"caption\":\"Selvagem\"},\"image\":{\"@id\":\"https:\\\/\\\/selvagemciclo.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/selvagem_ciclodeestudos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@selvagemciclo8\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sopro dos drag\u00f5es - Fran\u00e7a - Selvagem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/selvagemciclo.org.br\/en\/agenda\/sopro-dos-dragoes-franca-3\/","og_locale":"en_GB","og_type":"article","og_title":"Sopro dos drag\u00f5es - Fran\u00e7a - Selvagem","og_description":"Entre os dias 9 e 12 de setembro, acontece a s\u00e9rie de encontros \u201cO sopro dos drag\u00f5es: Di\u00e1logos interdisciplinares em torno das pot\u00eancias elementares\u201d, organizada pela Associa\u00e7\u00e3o Selvagem junto com a Universidade Sorbonne, \u00e0 convite da antrop\u00f3loga Nastassja Martin. O evento inclui 3 dias de programa\u00e7\u00e3o no Museu Departamental Albert-Kahn, em Paris, com falas de Cristine Taku\u00e1, Anna Dantes e Carlos Pap\u00e1, e uma noite no cinema com filmes da cole\u00e7\u00e3o KADIST e com as Flechas Selvagem, exibidas em di\u00e1logo com os artistas. O evento \u00e9 presencial e as inscri\u00e7\u00f5es s\u00e3o gratuitas.","og_url":"https:\/\/selvagemciclo.org.br\/en\/agenda\/sopro-dos-dragoes-franca-3\/","og_site_name":"Selvagem","og_image":[{"width":906,"height":906,"url":"https:\/\/selvagemciclo.org.br\/wp-content\/uploads\/2026\/08\/SD_LOGO2-e1787863731989.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/selvagemciclo.org.br\/agenda\/sopro-dos-dragoes-franca-3\/","url":"https:\/\/selvagemciclo.org.br\/agenda\/sopro-dos-dragoes-franca-3\/","name":"Sopro dos drag\u00f5es - Fran\u00e7a - Selvagem","isPartOf":{"@id":"https:\/\/selvagemciclo.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/selvagemciclo.org.br\/agenda\/sopro-dos-dragoes-franca-3\/#primaryimage"},"image":{"@id":"https:\/\/selvagemciclo.org.br\/agenda\/sopro-dos-dragoes-franca-3\/#primaryimage"},"thumbnailUrl":"https:\/\/selvagemciclo.org.br\/wp-content\/uploads\/2026\/08\/SD_LOGO2-e1787863731989.png","datePublished":"2026-09-01T21:24:03+00:00","breadcrumb":{"@id":"https:\/\/selvagemciclo.org.br\/agenda\/sopro-dos-dragoes-franca-3\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/selvagemciclo.org.br\/agenda\/sopro-dos-dragoes-franca-3\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/selvagemciclo.org.br\/agenda\/sopro-dos-dragoes-franca-3\/#primaryimage","url":"https:\/\/selvagemciclo.org.br\/wp-content\/uploads\/2026\/08\/SD_LOGO2-e1787863731989.png","contentUrl":"https:\/\/selvagemciclo.org.br\/wp-content\/uploads\/2026\/08\/SD_LOGO2-e1787863731989.png","width":906,"height":906,"caption":"O Sopro dos Drag\u00f5es"},{"@type":"BreadcrumbList","@id":"https:\/\/selvagemciclo.org.br\/agenda\/sopro-dos-dragoes-franca-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/selvagemciclo.org.br\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/selvagemciclo.org.br\/agenda\/"},{"@type":"ListItem","position":3,"name":"Sopro dos drag\u00f5es &#8211; Fran\u00e7a"}]},{"@type":"WebSite","@id":"https:\/\/selvagemciclo.org.br\/#website","url":"https:\/\/selvagemciclo.org.br\/","name":"Selvagem","description":"Ciclo de estudos sobre a vida","publisher":{"@id":"https:\/\/selvagemciclo.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/selvagemciclo.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/selvagemciclo.org.br\/#organization","name":"Selvagem","url":"https:\/\/selvagemciclo.org.br\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/selvagemciclo.org.br\/#\/schema\/logo\/image\/","url":"https:\/\/selvagemciclo.org.br\/wp-content\/uploads\/2026\/01\/cropped-ICONE_SELVAGEM_2026-1.png","contentUrl":"https:\/\/selvagemciclo.org.br\/wp-content\/uploads\/2026\/01\/cropped-ICONE_SELVAGEM_2026-1.png","width":512,"height":512,"caption":"Selvagem"},"image":{"@id":"https:\/\/selvagemciclo.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/selvagem_ciclodeestudos\/","https:\/\/www.youtube.com\/@selvagemciclo8"]}]}},"_links":{"self":[{"href":"https:\/\/selvagemciclo.org.br\/en\/wp-json\/wp\/v2\/tribe_events\/12817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/selvagemciclo.org.br\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/selvagemciclo.org.br\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/selvagemciclo.org.br\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/selvagemciclo.org.br\/en\/wp-json\/wp\/v2\/tribe_events\/12817\/revisions"}],"predecessor-version":[{"id":12818,"href":"https:\/\/selvagemciclo.org.br\/en\/wp-json\/wp\/v2\/tribe_events\/12817\/revisions\/12818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/selvagemciclo.org.br\/en\/wp-json\/wp\/v2\/media\/12741"}],"wp:attachment":[{"href":"https:\/\/selvagemciclo.org.br\/en\/wp-json\/wp\/v2\/media?parent=12817"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/selvagemciclo.org.br\/en\/wp-json\/wp\/v2\/tags?post=12817"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/selvagemciclo.org.br\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=12817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}